{"id":2187,"date":"2024-10-25T20:21:36","date_gmt":"2024-10-25T17:21:36","guid":{"rendered":"https:\/\/prochefmarket.com\/?p=2187"},"modified":"2024-10-29T13:27:21","modified_gmt":"2024-10-29T10:27:21","slug":"deprem-guvenligi-icin-hafif-celik-yapilar-neden-tercih-edilmeli","status":"publish","type":"post","link":"https:\/\/prochefmarket.com\/fr\/deprem-guvenligi-icin-hafif-celik-yapilar-neden-tercih-edilmeli\/","title":{"rendered":"Pourquoi les structures en acier l\u00e9ger devraient-elles \u00eatre pr\u00e9f\u00e9r\u00e9es pour la s\u00e9curit\u00e9 sismique ?"},"content":{"rendered":"<p>Les avantages des structures l\u00e9g\u00e8res en acier en mati\u00e8re de s\u00e9curit\u00e9 dans les r\u00e9gions \u00e0 haut risque sismique seront au centre de cet article. Dans l&#039;article, la protection contre les tremblements de terre offerte par les syst\u00e8mes en acier l\u00e9ger gr\u00e2ce \u00e0 leur flexibilit\u00e9 et leur r\u00e9sistance peut \u00eatre expliqu\u00e9e en d\u00e9tail. Il sera soulign\u00e9 que les structures en acier l\u00e9ger offrent de meilleures performances sismiques que les structures traditionnelles et peuvent \u00eatre une option s\u00fbre m\u00eame sur un sol faible. De plus, les normes d&#039;ing\u00e9nierie prises en compte lors du processus de conception des structures en acier l\u00e9ger et les d\u00e9tails techniques qui augmentent la durabilit\u00e9 de ces structures peuvent \u00e9galement \u00eatre expliqu\u00e9s. \u00c0 la fin de l&#039;article, l&#039;importance des conceptions de b\u00e2timents r\u00e9sistants aux tremblements de terre et la contribution des structures en acier l\u00e9ger \u00e0 cet \u00e9gard peuvent \u00eatre pr\u00e9sent\u00e9es plus concr\u00e8tement en s&#039;appuyant sur des exemples de projets.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les avantages des structures l\u00e9g\u00e8res en acier en mati\u00e8re de s\u00e9curit\u00e9 dans les r\u00e9gions \u00e0 haut risque sismique seront au centre de cet article. Dans l&#039;article, la protection contre les tremblements de terre offerte par les syst\u00e8mes en acier l\u00e9ger gr\u00e2ce \u00e0 leur flexibilit\u00e9 et leur r\u00e9sistance peut \u00eatre expliqu\u00e9e en d\u00e9tail. Il sera soulign\u00e9 que les structures en acier l\u00e9ger offrent de meilleures performances sismiques que les structures traditionnelles et peuvent \u00eatre une option s\u00fbre m\u00eame sur un sol faible. Aussi, la lumi\u00e8re<\/p>","protected":false},"author":1,"featured_media":2304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","wds_primary_category":0,"_joinchat":[],"footnotes":""},"categories":[22],"tags":[23,24],"class_list":["post-2187","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-deprem","tag-deprem","tag-hafif-celik-yapilar-neden-tercih-edilmeli","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/posts\/2187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/comments?post=2187"}],"version-history":[{"count":1,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/posts\/2187\/revisions"}],"predecessor-version":[{"id":2188,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/posts\/2187\/revisions\/2188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/media\/2304"}],"wp:attachment":[{"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/media?parent=2187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/categories?post=2187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochefmarket.com\/fr\/wp-json\/wp\/v2\/tags?post=2187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}